{"id":244483,"date":"2026-09-02T06:50:11","date_gmt":"2026-09-02T10:50:11","guid":{"rendered":"https:\/\/primicias.net\/web\/?p=244483"},"modified":"2026-09-02T06:50:11","modified_gmt":"2026-09-02T10:50:11","slug":"residentes-en-nyc-seran-multados-a-partir-de-septiembre-si-no-sacan-la-basura-en-contenedores","status":"publish","type":"post","link":"https:\/\/primicias.net\/web\/residentes-en-nyc-seran-multados-a-partir-de-septiembre-si-no-sacan-la-basura-en-contenedores\/","title":{"rendered":"Residentes en NYC ser\u00e1n multados a partir de septiembre si no sacan la basura en contenedores"},"content":{"rendered":"<p><b>NUEVA YORK.-<\/b>\u00a0El Departamento de Saneamiento de Nueva York (DSNY) anunci\u00f3 este fin de semana que los neoyorkinos, entre ellos decenas de miles de dominicanos, desde septiembre ser\u00e1 obligatorio usar un contenedor oficial para sacar la basura.<\/p>\n<p>Las multas comenzar\u00e1n el martes 8 de septiembre y pueden llegar hasta 200 d\u00f3lares, equivalente a 11,500 pesos dominicanos. La primera infracci\u00f3n tendr\u00e1 una multa de 50 d\u00f3lares, aumentando progresivamente para reincidentes.<\/p>\n<p>Se busca modernizar la recolecci\u00f3n y reducir la basura en las aceras. Afecta a edificios residenciales de una a nueve viviendas. Los contenedores oficiales cuestan entre 45 y 55 d\u00f3lares y est\u00e1n disponibles en Home Depot y en l\u00ednea.<\/p>\n<p>Tambi\u00e9n existe la posibilidad de pedirlos por internet mediante servicios de entrega.\u00a0<b>Ver =<\/b>\u00a0<a href=\"https:\/\/www.nyc.gov\/site\/dsny\/collection\/containerization\/nyc-bins.page\" target=\"_blank\" rel=\"nofollow noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nyc.gov\/site\/dsny\/collection\/containerization\/nyc-bins.page&amp;source=gmail&amp;ust=1788400264896000&amp;usg=AOvVaw3p2abHP08MJEeew6TVMxku\">https:\/\/www.nyc.gov\/site\/dsny\/<wbr \/>collection\/containerization\/<wbr \/>nyc-bins.page<\/a><\/p>\n<p>La medida forma parte de la estrategia de la ciudad para modernizar la recolecci\u00f3n de residuos y reducir la presencia de bolsas de basura expuestas en las aceras, un problema especialmente visible en algunas zonas de los cinco condados.<\/p>\n<p>La nueva exigencia est\u00e1 dirigida a los propietarios de edificios residenciales con entre una y 9 viviendas. Esto incluye desde casas unifamiliares hasta peque\u00f1as propiedades multifamiliares.<\/p>\n<p>Los contenedores oficiales ya pueden adquirirse en las tiendas Home Depot de los 5 condados. Tambi\u00e9n existe la posibilidad de pedirlos por internet mediante servicios de entrega.<\/p>\n<p><b>Ver =<\/b>\u00a0<a href=\"https:\/\/www.nyc.gov\/site\/dsny\/collection\/containerization\/nyc-bins.page\" target=\"_blank\" rel=\"nofollow noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nyc.gov\/site\/dsny\/collection\/containerization\/nyc-bins.page&amp;source=gmail&amp;ust=1788400264897000&amp;usg=AOvVaw0YujHLCcQ6f7lZD7xYXl1n\">https:\/\/www.nyc.gov\/site\/dsny\/<wbr \/>collection\/containerization\/<wbr \/>nyc-bins.page<\/a><\/p>\n<p>En NYC, hay aproximadamente 950.000 edificios exclusivamente residenciales y unos 65.000 de uso mixto, residencial y comercial. \u00a0 En Queens hay unos 395.000 edificios con viviendas; en Brooklyn 285.000; en Staten Island alrededor de 145.000; en El Bronx unos 115.000 y en Manhattan cerca de 75.000.<\/p>\n<p>En los sectores de mayor concentraci\u00f3n de dominicanos, Washington Heights tiene alrededor de 750, mientras en Inwood unos 370 edificios residenciales, que suman 1.100, con m\u00e1s de 47 mil viviendas en total.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUEVA YORK.-\u00a0El Departamento de Saneamiento de Nueva York (DSNY) anunci\u00f3 este fin de semana que los neoyorkinos, entre ellos decenas de miles de dominicanos, desde septiembre ser\u00e1 obligatorio usar un contenedor oficial para sacar la basura. Las multas comenzar\u00e1n el martes 8 de septiembre y pueden llegar hasta 200 d\u00f3lares, equivalente a 11,500 pesos dominicanos. &hellip;<\/p>\n","protected":false},"author":11,"featured_media":244484,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37,38],"tags":[],"class_list":["post-244483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diaspora","category-new-york"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/primicias.net\/web\/wp-content\/uploads\/2026\/09\/Residentes-en-NYC-seran-multados-a-partir-de-septiembre-si-no-sacan-la-basura-en-contenedores.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts\/244483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/comments?post=244483"}],"version-history":[{"count":1,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts\/244483\/revisions"}],"predecessor-version":[{"id":244487,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts\/244483\/revisions\/244487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/media\/244484"}],"wp:attachment":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/media?parent=244483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/categories?post=244483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/tags?post=244483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}