{"id":244470,"date":"2026-09-01T21:24:34","date_gmt":"2026-09-02T01:24:34","guid":{"rendered":"https:\/\/primicias.net\/web\/?p=244470"},"modified":"2026-09-01T21:24:34","modified_gmt":"2026-09-02T01:24:34","slug":"es-mala-suerte-o-mala-decision","status":"publish","type":"post","link":"https:\/\/primicias.net\/web\/es-mala-suerte-o-mala-decision\/","title":{"rendered":"Es mala suerte o mala decisi\u00f3n"},"content":{"rendered":"<p><b>Lic. Luis Ma. Ruiz Pou<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La mala suerte se refiere a la ocurrencia de eventos desafortunados o adversos que parecen suceder de manera inesperada o fuera del control de la persona, donde los resultados no son los deseados y parecen ocurrir sin explicaci\u00f3n l\u00f3gica. Puede manifestarse en distintos \u00e1mbitos de la vida, como el trabajo, la salud o las relaciones personales, y se asocia con la falta de fortuna o con circunstancias que escapan al control del individuo. (Dicc. Encicl\u00f3pedico Espa\u00f1ol)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, las malas decisiones son una parte inevitable de la experiencia humana, afectando desde nuestras finanzas personales hasta nuestras relaciones y carreras. Comprender qu\u00e9 son y c\u00f3mo manejarlas, es crucial para el liderazgo efectivo y el desarrollo personal. Las decisiones, buenas o malas, no son simplemente elecciones racionales; est\u00e1n profundamente influenciadas por una variedad de factores psicol\u00f3gicos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Buscando volver a ser grande nuevamente, Wahsington ha sido victima de sus malas suertes o malas desiciones. Ha fracasado en varios escenarios; primero, intentent\u00f3 controlar el Canal de Panam\u00e1, anexar a Canad\u00e1 a Estados Unidos como un estado m\u00e1s, comprar a Greoeslandia y controlar a Mexico. En adici\u00f3n, invadio a Venezuela para secuestrar a su presidente y m\u00e1s adelante, pone en su agenda a Cuba.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todo esto, el conflicto en el Medio Oriente con la guerra contra el Estado Isl\u00e1mico de ir\u00e1n, para apoyar al el Estado sionista de Israel, cometiendo el gran error de aceptar los consejos del Primer Ministro israel\u00ed, Benjam\u00edn Netanyahu, quien sobre la base de un falso informe de su organismo de inteligencia, de que Ir\u00e1n estaba cerca de fabricar un misil nuclear; por lo que les recomend\u00f3 iniciar un bombardeo contra el pueblo iran\u00ed.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una de las consecuencia de ese ataque, fue el asesinato de 168 estudiantes hembras y varones que en esos momentos recibian instrucciones educativas. \u00a1\u00a1\u00a1Eso no fue mala suerte, fue una mala decisi\u00f3n!!! En el caso de Venezuela con el expediente de Nicol\u00e1s Maduro, la prensa rese\u00f1a que es un caso que podr\u00eda fracasar, porque se violaron leyes y regalmentos internacional que impide hacer preso a un gobernante rebestido de inmunidad diplom\u00e1tica.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Recientemente, el Congreso de EUA, emiti\u00f3 un resoluci\u00f3n con un llamado al actual gobierno venezolano, para que se abtenga de replesaria a candidatos de la oposici\u00f3n, especialmente el caso de Mar\u00eda Cortna Machado. \u00a1Oh! Pero que casualidad. Wahsington se olvido del presidente legitimo Edmundo Gonzales. Para Donald Trump, Edmundo es un muerto pol\u00edtico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La resoluci\u00f3n del congreso, legitima la administraci\u00f3n del secuestrado Nicol\u00e1s Maduro Moro, ya que Daysi Rodr\u00edguez, era la vicepresidente de Venezuela en momento de que Maduro era el jefe de gobierno. Este es otro caso; no fue por mala suerte, fue por mala desici\u00f3n de Donald Trump, un hombre que habla, actua y pienasa desp\u00faes. El mejor ejemplo de esto, es el trapi\u00e9s en el manejo de las negociaciones con Ir\u00e1n, buscando la apertura del Estrecho Ormuz, la caja donde sera sepultada la pol\u00edtica errada de Washington.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Recordemos que cuando Trump llego en enero del 2025 a la Casa Blanca, se comprometei\u00f3 a cabar de forma inmediata la guerra entre Rusia y Ucrania. Lograr un acuerdo entre Kiev y Mosc\u00fa en menos de 24 horas. Fue una falta de experiencia o una exageraci\u00f3n t\u00edpica del presidente estadounidense que, gusta mucho estar frente a un micr\u00f3fono.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No es la mala suerte la que hunde a Washington, sino la mala decisi\u00f3n de l\u00edderes que confunden poder con improvisaci\u00f3n, diplomacia con fuerza e institucionalidad con capricho. Mientras Estados Unidos insista en actuar primero y pensar despu\u00e9s, su pol\u00edtica exterior seguir\u00e1 escribiendo epitafios en las aulas destruidas de Ir\u00e1n, en las calles de Caracas y en las aguas turbulentas del Estrecho de Ormuz. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lic. Luis Ma. Ruiz Pou La mala suerte se refiere a la ocurrencia de eventos desafortunados o adversos que parecen suceder de manera inesperada o fuera del control de la persona, donde los resultados no son los deseados y parecen ocurrir sin explicaci\u00f3n l\u00f3gica. Puede manifestarse en distintos \u00e1mbitos de la vida, como el trabajo, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":202542,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[49],"tags":[],"class_list":["post-244470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/primicias.net\/web\/wp-content\/uploads\/2025\/10\/LUIS-RUIZ-300.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts\/244470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/comments?post=244470"}],"version-history":[{"count":1,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts\/244470\/revisions"}],"predecessor-version":[{"id":244471,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/posts\/244470\/revisions\/244471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/media\/202542"}],"wp:attachment":[{"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/media?parent=244470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/categories?post=244470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primicias.net\/web\/wp-json\/wp\/v2\/tags?post=244470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}